{"id":190,"date":"2014-05-11T23:31:40","date_gmt":"2014-05-11T21:31:40","guid":{"rendered":"http:\/\/pffft.fr\/wp3\/?p=190"},"modified":"2014-05-13T01:58:53","modified_gmt":"2014-05-12T23:58:53","slug":"imprimez-le-bulletin-de-vote","status":"publish","type":"post","link":"http:\/\/pffft.fr\/wp3\/2014\/05\/11\/imprimez-le-bulletin-de-vote\/","title":{"rendered":"Imprimez le bulletin de vote"},"content":{"rendered":"<p><a href=\"http:\/\/pffft.fr\/wp3\/wp-content\/uploads\/2014\/05\/bulletin_2.pdf\">T\u00e9l\u00e9chargez<\/a> puis imprimez le bulletin de vote pour les \u00e9lections europ\u00e9ennes ! (la feuille comporte deux bulletins sur une feuille A4, \u00e0 d\u00e9couper au milieu &#8211; un bulletin dans l&rsquo;urne, un autre pour votre grand-m\u00e8re pour qu&rsquo;elle puisse voter PFT elle aussi)<\/p>\n<p>Voir aussi le PFT dans la\u00a0<a href=\"http:\/\/pffft.fr\/wp3\/revue-de-presse\/\">presse r\u00e9cente<\/a>.<\/p>\n<p>Retrouvez-nous \u00e9galement sur Facebook !<br \/>\n<iframe src=\"\/\/www.facebook.com\/plugins\/like.php?href=https%3A%2F%2Fwww.facebook.com%2FPartifaireuntour&amp;width&amp;layout=button_count&amp;action=like&amp;show_faces=true&amp;share=true&amp;height=21\" scrolling=\"no\" frameborder=\"0\" style=\"border:none; overflow:hidden; height:21px;\" allowTransparency=\"true\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>T\u00e9l\u00e9chargez puis imprimez le bulletin de vote pour les \u00e9lections europ\u00e9ennes ! (la feuille comporte deux bulletins sur une feuille A4, \u00e0 d\u00e9couper au milieu &#8211; un bulletin dans l&rsquo;urne, un autre pour votre grand-m\u00e8re pour qu&rsquo;elle puisse voter PFT elle aussi) Voir aussi le PFT dans la\u00a0presse r\u00e9cente. Retrouvez-nous \u00e9galement sur Facebook ! &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-190","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"http:\/\/pffft.fr\/wp3\/wp-json\/wp\/v2\/posts\/190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/pffft.fr\/wp3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/pffft.fr\/wp3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/pffft.fr\/wp3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/pffft.fr\/wp3\/wp-json\/wp\/v2\/comments?post=190"}],"version-history":[{"count":13,"href":"http:\/\/pffft.fr\/wp3\/wp-json\/wp\/v2\/posts\/190\/revisions"}],"predecessor-version":[{"id":255,"href":"http:\/\/pffft.fr\/wp3\/wp-json\/wp\/v2\/posts\/190\/revisions\/255"}],"wp:attachment":[{"href":"http:\/\/pffft.fr\/wp3\/wp-json\/wp\/v2\/media?parent=190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/pffft.fr\/wp3\/wp-json\/wp\/v2\/categories?post=190"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/pffft.fr\/wp3\/wp-json\/wp\/v2\/tags?post=190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}